{"id":334,"date":"2021-10-27T10:12:08","date_gmt":"2021-10-27T08:12:08","guid":{"rendered":"https:\/\/www.famigliapaolina.net\/preghierapaolina\/?post_type=le-liturgie&#038;p=334"},"modified":"2021-11-16T17:23:09","modified_gmt":"2021-11-16T16:23:09","slug":"lodi-mattutine","status":"publish","type":"le-liturgie","link":"https:\/\/www.famigliapaolina.net\/preghierapaolina\/le-liturgie\/30-giugno-san-paolo-apostolo\/lodi-mattutine\/","title":{"rendered":"Lodi mattutine"},"content":{"rendered":"<p><strong><span style=\"color: #800000;\">INNO<\/span><\/strong><\/p>\n<p>O Paolo, profeta e maestro,<br \/>\nl&#8217;invito tuo ardente ci esorta:<br \/>\n\u00ab Cercate le cose di Dio,<br \/>\ngustate quei beni sublimi\u00bb.<\/p>\n<p>Crediamo l&#8217;umana esistenza<br \/>\nanticipo e attesa del cielo;<br \/>\nsperando con te noi bramiamo<br \/>\nvestirci del corpo celeste.<\/p>\n<p>Sia gloria perenne al Dio trino,<br \/>\nonore, potenza, esultanza;<br \/>\ncos\u00ec come adesso per sempre<br \/>\nnei secoli eterni \u00e8 il Signore. Amen.<\/p>\n<h6><span style=\"color: #800000;\">Oppure un altro inno o canto adatto, approvato dall&#8217;autorit\u00e0 competente.\u00a0<\/span><\/h6>\n<p>&nbsp;<\/p>\n<p><em><span style=\"color: #800000;\">1<\/span> <span style=\"color: #800000;\">ant.<\/span><\/em> Nessuno ha un amore pi\u00f9 grande<br \/>\ndi colui che offre la vita per i suoi amici.<\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #800000;\"><strong>SALMO 62,2-9\u00a0\u00a0\u00a0\u00a0 L\u2019anima assetata di Dio<\/strong><\/span><\/p>\n<p><em>La chiesa ha sete del suo Salvatore, bramando di dissetarsi alla fonte dell\u2019acqua viva che zampilla per la vita eterna<\/em>\u00a0(cf Cassiodoro).<\/p>\n<p>&nbsp;<\/p>\n<p>O Dio, tu sei il mio Dio, all\u2019aurora ti cerco, *<br \/>\ndi te ha sete l\u2019anima mia,<br \/>\na te anela la mia carne, *<br \/>\ncome terra deserta, arida, senz\u2019acqua.<\/p>\n<p>Cos\u00ec nel santuario ti ho cercato, *<br \/>\nper contemplare la tua potenza e la tua gloria.<br \/>\nPoich\u00e9 la tua grazia vale pi\u00f9 della vita, *<br \/>\nle mie labbra diranno la tua lode.<\/p>\n<p>Cos\u00ec ti benedir\u00f2 finch\u00e9 io viva, *<br \/>\nnel tuo nome alzer\u00f2 le mie mani.<br \/>\nMi sazier\u00f2 come a lauto convito, *<br \/>\ne con voci di gioia ti loder\u00e0 la mia bocca.<\/p>\n<p>Nel mio giaciglio di te mi ricordo, *<br \/>\npenso a te nelle veglie notturne,<br \/>\ntu sei stato il mio aiuto; *<br \/>\nesulto di gioia all\u2019ombra delle tue ali.<\/p>\n<p>A te si stringe *<br \/>\nl\u2019anima mia.<br \/>\nLa forza della tua destra *<br \/>\nmi sostiene.<\/p>\n<p>&nbsp;<\/p>\n<p><em><span style=\"color: #800000;\">1<\/span> <span style=\"color: #800000;\">ant.<\/span><\/em> Nessuno ha un amore pi\u00f9 grande<br \/>\ndi colui che offre la vita per i suoi amici.<\/p>\n<p><em><span style=\"color: #800000;\">2 ant<\/span><\/em>. Mi vanto volentieri delle mie debolezze,<br \/>\nperch\u00e9 dimori in me la potenza di Cristo.<\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #800000;\"><strong>CANTICO\u00a0<\/strong>(Dn 3.57-88.56)\u00a0<strong>Ogni creatura lodi il Signore<\/strong><\/span><\/p>\n<p><em>Lodate il nostro Dio, voi tutti suoi servi<\/em>\u00a0(Ap 19,5).<\/p>\n<p>&nbsp;<\/p>\n<p>Benedite, opere tutte del Signore, il Signore, *<br \/>\nlodatelo ed esaltatelo nei secoli.<br \/>\nBenedite, angeli del Signore, il Signore, *<br \/>\nbenedite, cieli, il Signore.<\/p>\n<p>Benedite, acque tutte, che siete sopra i cieli, il Signore, *<br \/>\nbenedite, potenze tutte del Signore, il Signore.<br \/>\nBenedite, sole e luna, il Signore, *<br \/>\nbenedite, stelle del cielo, il Signore.<\/p>\n<p>Benedite, piogge e rugiade, il Signore, *<br \/>\nbenedite, o venti tutti, il Signore.<br \/>\nBenedite, fuoco e calore, il Signore, *<br \/>\nbenedite, freddo e caldo, il Signore.<\/p>\n<p>Benedite, rugiada e brina, il Signore, *<br \/>\nbenedite, gelo e freddo, il Signore.<br \/>\nBenedite, ghiacci e nevi, il Signore, *<br \/>\nbenedite, notti e giorni, il Signore.<\/p>\n<p>Benedite, luce e tenebre, il Signore, *<br \/>\nbenedite, folgori e nubi, il Signore.<br \/>\nBenedica la terra il Signore, *<br \/>\nlo lodi e lo esalti nei secoli.<\/p>\n<p>Benedite, monti e colline, il Signore, *<br \/>\nbenedite, creature tutte che germinate sulla terra, il Signore.<br \/>\nBenedite, sorgenti, il Signore, *<br \/>\nbenedite, mari e fiumi, il Signore.<\/p>\n<p>Benedite, mostri marini<br \/>\ne quanto si muove nell\u2019acqua, il Signore, *<br \/>\nbenedite, uccelli tutti dell\u2019aria, il Signore.<br \/>\nBenedite, animali tutti, selvaggi e domestici, il Signore, *<br \/>\nbenedite, figli dell\u2019uomo, il Signore.<\/p>\n<p>Benedica Israele il Signore, *<br \/>\nlo lodi e lo esalti nei secoli.<br \/>\nBenedite, sacerdoti del Signore, il Signore, *<br \/>\nbenedite, o servi del Signore, il Signore.<\/p>\n<p>Benedite, spiriti e anime dei giusti, il Signore, *<br \/>\nbenedite, pii e umili di cuore, il Signore.<br \/>\nBenedite, Anania, Azaria e Misaele, il Signore, *<br \/>\nlodatelo ed esaltatelo nei secoli.<\/p>\n<p>Benediciamo il Padre e il Figlio con lo Spirito Santo, *<br \/>\nlodiamolo ed esaltiamolo nei secoli.<br \/>\nBenedetto sei tu, Signore, nel firmamento del cielo, *<br \/>\ndegno di lode e di gloria nei secoli.<\/p>\n<p><span style=\"color: #800000;\">Alla fine di questo cantico non si dice il\u00a0<\/span>Gloria al Padre.<\/p>\n<p>&nbsp;<\/p>\n<p><em><span style=\"color: #800000;\">2 ant<\/span><\/em>. Mi vanto volentieri delle mie debolezze,<br \/>\nperch\u00e9 dimori in me la potenza di Cristo.<\/p>\n<p><em><span style=\"color: #800000;\">3 ant.<\/span><\/em> La grazia di Dio in me non fu vana;<br \/>\nla grazia di Dio non mi abbandona.<\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #800000;\"><strong>SALMO 149\u00a0\u00a0\u00a0\u00a0 Festa degli amici di Dio<\/strong><\/span><\/p>\n<p><em>I figli della Chiesa, i figli del nuovo popolo esultino nel loro re, Cristo<\/em>\u00a0(Esichio).<\/p>\n<p>&nbsp;<\/p>\n<p>Cantate al Signore un canto nuovo; *<br \/>\nla sua lode nell\u2019assemblea dei fedeli.<br \/>\nGioisca Israele nel suo Creatore, *<br \/>\nesultino nel loro Re i figli di Sion.<\/p>\n<p>Lodino il suo nome con danze, *<br \/>\ncon timpani e cetre gli cantino inni.<br \/>\nIl Signore ama il suo popolo, *<br \/>\nincorona gli umili di vittoria.<\/p>\n<p>Esultino i fedeli nella gloria, *<br \/>\nsorgano lieti dai loro giacigli.<br \/>\nLe lodi di Dio sulla loro bocca *<br \/>\ne la spada a due tagli nelle loro mani,<\/p>\n<p>per compiere la vendetta tra i popoli *<br \/>\ne punire le genti;<br \/>\nper stringere in catene i loro capi, *<br \/>\ni loro nobili in ceppi di ferro;<\/p>\n<p>per eseguire su di essi *<br \/>\nil giudizio gi\u00e0 scritto:<br \/>\nquesta \u00e8 la gloria *<br \/>\nper tutti i suoi fedeli.<\/p>\n<p>&nbsp;<\/p>\n<p><em><span style=\"color: #800000;\">3 ant.<\/span><\/em> La grazia di Dio in me non fu vana;<br \/>\nla grazia di Dio non mi abbandona.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #800000;\"><strong>LETTURA BREVE<\/strong><\/span><br \/>\n<span style=\"color: #800000;\">2Tm 4.7.8<\/span><\/p>\n<p>Ho combattuto la buona battaglia, ho terminato la mia corsa, ho conservato la fede. Ora mi resta solo la corona di giustizia che il Signore, giusto giudice, mi consegner\u00e0 in quel giorno; e non solo a me, ma anche a tutti coloro che attendono con amore la sua manifestazione.<\/p>\n<p>&nbsp;<\/p>\n<p><strong><span style=\"color: #800000;\">RESPONSORIO BREVE<\/span><\/strong><\/p>\n<p><span style=\"color: #800000;\">R\/.<\/span> Tu sei vaso di elezione, * san Paolo apostolo.<br \/>\nTu sei vaso di elezione, san Paolo apostolo.<\/p>\n<p><span style=\"color: #800000;\">V\/.<\/span> \u00a0Predicatore della verit\u00e0 in tutto il mondo,<br \/>\nsan Paolo apostolo.<\/p>\n<p>Gloria al Padre e al Figlio e allo Spirito Santo.<br \/>\nTu sei vaso di elezione, san Paolo apostolo.<\/p>\n<p>&nbsp;<\/p>\n<p><em><span style=\"color: #800000;\">Ant. al Ben.<\/span> <\/em>Mi sono fatto tutto a tutti,<br \/>\nperch\u00e9 tutti siano salvi.<\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #800000;\"><strong>CANTICO DI ZACCARIA\u00a0\u00a0 (Benedictus)<\/strong>\u00a0\u00a0\u00a0 Lc 1,68 79<\/span><\/p>\n<p>Benedetto il Signore Dio d\u2019Israele, *<br \/>\nperch\u00e9 ha visitato e redento il suo popolo,<\/p>\n<p>e ha suscitato per noi una salvezza potente *<br \/>\nnella casa di Davide, suo servo,<\/p>\n<p>come aveva promesso *<br \/>\nper bocca dei suoi santi profeti d<sup>\u2019<\/sup>un tempo:<\/p>\n<p>salvezza dai nostri nemici, *<br \/>\ne dalle mani di quanti ci odiano.<\/p>\n<p>Cos\u00ec egli ha concesso misericordia ai nostri padri *<br \/>\ne si \u00e8 ricordato della sua santa alleanza,<\/p>\n<p>del giuramento fatto ad Abramo, nostro padre, *<br \/>\ndi concederci, liberati dalle mani dei nemici,<\/p>\n<p>di servirlo senza timore, in santit\u00e0 e giustizia *<br \/>\nal suo cospetto, per tutti i nostri giorni.<\/p>\n<p>E tu, bambino, sarai chiamato profeta dell\u2019Altissimo *<br \/>\nperch\u00e9 andrai innanzi al Signore a preparargli le strade,<\/p>\n<p>per dare al suo popolo la conoscenza della salvezza *<br \/>\nnella remissione dei suoi peccati,<\/p>\n<p>grazie alla bont\u00e0 misericordiosa del nostro Dio, *<br \/>\nper cui verr\u00e0 a visitarci dall\u2019alto un sole che sorge,<\/p>\n<p>per rischiarare quelli che stanno nelle tenebre *<br \/>\ne nell\u2019ombra della morte<\/p>\n<p>e dirigere i nostri passi *<br \/>\nsulla via della pace.<\/p>\n<p>&nbsp;<\/p>\n<p><em><span style=\"color: #800000;\">Ant. al Ben.<\/span> <\/em>Mi sono fatto tutto a tutti,<br \/>\nperch\u00e9 tutti siano salvi<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong><span style=\"color: #800000;\">INVOCAZIONI<\/span><\/strong><\/p>\n<p>Per mezzo degli apostoli il Signore Ges\u00f9, risorto dai morti, ci ha fatti eredi del regno dei cieli. Riconoscia\u00admo tutti i suoi benefici, acclamando:<br \/>\n<em>Ti loda, Signore il coro degli apostoli<\/em><\/p>\n<p>Sii benedetto, Ges\u00f9, che nella tua misericordia hai reso san Paolo ardente apostolo della Chiesa,<br \/>\n\u2014 donaci, per sua intercessione, la vera conversione del cuore e una piena configurazione a te.<\/p>\n<p>Sii benedetto, Ges\u00f9, per aver eletto l&#8217;apostolo Paolo a modello e predicatore della santa verginit\u00e0,<br \/>\n\u2014\u00a0 donaci di conoscere, amare e servire soltanto te, uni\u00adco Signore e Maestro.<\/p>\n<p>Sii benedetto, Ges\u00f9, per aver dato in san Paolo un mo\u00addello di perfetta obbedienza,<br \/>\n\u2014\u00a0 per sua intercessione concedi a noi tuoi discepoli di obbedire al Padre come te, nell&#8217;amore.<\/p>\n<p>Sii benedetto, Ges\u00f9, per averci insegnato in san Paolo la vera povert\u00e0,<br \/>\n\u2014\u00a0 concedici di saper perdere tutto per possedere te che sei la Via, la Verit\u00e0 e la Vita.<\/p>\n<p>Sii benedetto, Ges\u00f9, che hai colmato il cuore di san Pao\u00adlo di zelo e di amore per la tua Chiesa,<br \/>\n\u2014\u00a0 riempi i nostri cuori della tua carit\u00e0.<\/p>\n<p>Sii benedetto, Ges\u00f9, per aver scelto e mandato l&#8217;apostolo Paolo a tutte le genti,<br \/>\n\u2014\u00a0 apri le nostre menti alla tua Parola affinch\u00e9 possia\u00admo portare il vangelo in ogni popolo e lingua.<\/p>\n<p>Padre nostro.<\/p>\n<p>&nbsp;<\/p>\n<p><strong><span style=\"color: #800000;\">ORAZIONE<\/span><\/strong><\/p>\n<p>Signore, Dio nostro, che nel tuo amore per gli uomini hai scelto e inviato l&#8217;apostolo Paolo ad annunciare il Vangelo di Ges\u00f9 Cristo morto e risorto, concedi a noi, che lo onoriamo ispiratore e padre, di imitarlo nel porta\u00adre la Parola che salva agli uomini del nostro tempo. Per il nostro Signore.<\/p>\n<p>&nbsp;<\/p>\n<p>Il Signore ci benedica, ci preservi da ogni male<br \/>\ne ci con\u00adduca alla vita eterna.<\/p>\n<p><span style=\"color: #800000;\">R\/.\u00a0<\/span>Amen.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"featured_media":0,"parent":276,"menu_order":3,"template":"","acf":{"attachment_list":false,"hide_wp_ba":false,"acf_hide_title":false},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v17.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Lodi mattutine - Preghiera Paolina<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.famigliapaolina.net\/preghierapaolina\/le-liturgie\/30-giugno-san-paolo-apostolo\/lodi-mattutine\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lodi mattutine - Preghiera Paolina\" \/>\n<meta property=\"og:description\" content=\"INNO O Paolo, profeta e maestro, l&#8217;invito tuo ardente ci esorta: \u00ab Cercate le cose di Dio, gustate quei beni sublimi\u00bb. Crediamo l&#8217;umana esistenza anticipo e attesa del cielo; sperando con te noi bramiamo vestirci del corpo celeste. Sia gloria perenne al Dio trino, onore, potenza, esultanza; cos\u00ec come adesso per sempre nei secoli eterni \u00e8 il Signore. Amen. Oppure un altro inno o canto &hellip; Continua a leggere Lodi mattutine &raquo;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.famigliapaolina.net\/preghierapaolina\/le-liturgie\/30-giugno-san-paolo-apostolo\/lodi-mattutine\/\" \/>\n<meta property=\"og:site_name\" content=\"Preghiera Paolina\" \/>\n<meta property=\"article:modified_time\" content=\"2021-11-16T16:23:09+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.famigliapaolina.net\/preghierapaolina\/#website\",\"url\":\"https:\/\/www.famigliapaolina.net\/preghierapaolina\/\",\"name\":\"Preghiera Paolina\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.famigliapaolina.net\/preghierapaolina\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.famigliapaolina.net\/preghierapaolina\/le-liturgie\/30-giugno-san-paolo-apostolo\/lodi-mattutine\/#webpage\",\"url\":\"https:\/\/www.famigliapaolina.net\/preghierapaolina\/le-liturgie\/30-giugno-san-paolo-apostolo\/lodi-mattutine\/\",\"name\":\"Lodi mattutine - Preghiera Paolina\",\"isPartOf\":{\"@id\":\"https:\/\/www.famigliapaolina.net\/preghierapaolina\/#website\"},\"datePublished\":\"2021-10-27T08:12:08+00:00\",\"dateModified\":\"2021-11-16T16:23:09+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.famigliapaolina.net\/preghierapaolina\/le-liturgie\/30-giugno-san-paolo-apostolo\/lodi-mattutine\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.famigliapaolina.net\/preghierapaolina\/le-liturgie\/30-giugno-san-paolo-apostolo\/lodi-mattutine\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.famigliapaolina.net\/preghierapaolina\/le-liturgie\/30-giugno-san-paolo-apostolo\/lodi-mattutine\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.famigliapaolina.net\/preghierapaolina\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Liturgie\",\"item\":\"https:\/\/www.famigliapaolina.net\/preghierapaolina\/le-liturgie\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"30 giugno &#8211; SAN PAOLO APOSTOLO\",\"item\":\"https:\/\/www.famigliapaolina.net\/preghierapaolina\/le-liturgie\/30-giugno-san-paolo-apostolo\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Lodi mattutine\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lodi mattutine - Preghiera Paolina","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.famigliapaolina.net\/preghierapaolina\/le-liturgie\/30-giugno-san-paolo-apostolo\/lodi-mattutine\/","og_locale":"it_IT","og_type":"article","og_title":"Lodi mattutine - Preghiera Paolina","og_description":"INNO O Paolo, profeta e maestro, l&#8217;invito tuo ardente ci esorta: \u00ab Cercate le cose di Dio, gustate quei beni sublimi\u00bb. Crediamo l&#8217;umana esistenza anticipo e attesa del cielo; sperando con te noi bramiamo vestirci del corpo celeste. Sia gloria perenne al Dio trino, onore, potenza, esultanza; cos\u00ec come adesso per sempre nei secoli eterni \u00e8 il Signore. Amen. Oppure un altro inno o canto &hellip; Continua a leggere Lodi mattutine &raquo;","og_url":"https:\/\/www.famigliapaolina.net\/preghierapaolina\/le-liturgie\/30-giugno-san-paolo-apostolo\/lodi-mattutine\/","og_site_name":"Preghiera Paolina","article_modified_time":"2021-11-16T16:23:09+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"7 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/www.famigliapaolina.net\/preghierapaolina\/#website","url":"https:\/\/www.famigliapaolina.net\/preghierapaolina\/","name":"Preghiera Paolina","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.famigliapaolina.net\/preghierapaolina\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.famigliapaolina.net\/preghierapaolina\/le-liturgie\/30-giugno-san-paolo-apostolo\/lodi-mattutine\/#webpage","url":"https:\/\/www.famigliapaolina.net\/preghierapaolina\/le-liturgie\/30-giugno-san-paolo-apostolo\/lodi-mattutine\/","name":"Lodi mattutine - Preghiera Paolina","isPartOf":{"@id":"https:\/\/www.famigliapaolina.net\/preghierapaolina\/#website"},"datePublished":"2021-10-27T08:12:08+00:00","dateModified":"2021-11-16T16:23:09+00:00","breadcrumb":{"@id":"https:\/\/www.famigliapaolina.net\/preghierapaolina\/le-liturgie\/30-giugno-san-paolo-apostolo\/lodi-mattutine\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.famigliapaolina.net\/preghierapaolina\/le-liturgie\/30-giugno-san-paolo-apostolo\/lodi-mattutine\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.famigliapaolina.net\/preghierapaolina\/le-liturgie\/30-giugno-san-paolo-apostolo\/lodi-mattutine\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.famigliapaolina.net\/preghierapaolina\/"},{"@type":"ListItem","position":2,"name":"Liturgie","item":"https:\/\/www.famigliapaolina.net\/preghierapaolina\/le-liturgie\/"},{"@type":"ListItem","position":3,"name":"30 giugno &#8211; SAN PAOLO APOSTOLO","item":"https:\/\/www.famigliapaolina.net\/preghierapaolina\/le-liturgie\/30-giugno-san-paolo-apostolo\/"},{"@type":"ListItem","position":4,"name":"Lodi mattutine"}]}]}},"wpml_current_locale":"it_IT","wpml_translations":[{"locale":"fr_FR","id":567,"post_title":"Laudes","href":"https:\/\/www.famigliapaolina.net\/preghierapaolina\/\/30-juin-saint-paul-apotre\/matin\/?lang=fr\/"},{"locale":"es_ES","id":782,"post_title":"Laudes","href":"https:\/\/www.famigliapaolina.net\/preghierapaolina\/\/30-junio-san-pablo-apostol\/laudes\/?lang=es\/"},{"locale":"ko_KR","id":2699,"post_title":"\uc544\uce68\uae30\ub3c4","href":"https:\/\/www.famigliapaolina.net\/preghierapaolina\/\/6%ec%9b%94-30%ec%9d%bc-%ec%84%b1-%eb%b0%94%ec%98%a4%eb%a1%9c-%ec%82%ac%eb%8f%84-%eb%8c%80%ec%b6%95%ec%9d%bc%ed%99%8d\/%ec%95%84%ec%b9%a8%ea%b8%b0%eb%8f%84\/?lang=ko\/"}],"_links":{"self":[{"href":"https:\/\/www.famigliapaolina.net\/preghierapaolina\/wp-json\/wp\/v2\/le-liturgie\/334"}],"collection":[{"href":"https:\/\/www.famigliapaolina.net\/preghierapaolina\/wp-json\/wp\/v2\/le-liturgie"}],"about":[{"href":"https:\/\/www.famigliapaolina.net\/preghierapaolina\/wp-json\/wp\/v2\/types\/le-liturgie"}],"up":[{"embeddable":true,"href":"https:\/\/www.famigliapaolina.net\/preghierapaolina\/wp-json\/wp\/v2\/le-liturgie\/276"}],"wp:attachment":[{"href":"https:\/\/www.famigliapaolina.net\/preghierapaolina\/wp-json\/wp\/v2\/media?parent=334"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}